{"id":13619,"date":"2024-10-27T23:29:08","date_gmt":"2024-10-27T22:29:08","guid":{"rendered":"http:\/\/lawfactory-frankfurt.de\/?page_id=13619"},"modified":"2024-12-25T23:40:34","modified_gmt":"2024-12-25T22:40:34","slug":"zwangsvollstreckung-und-inkasso","status":"publish","type":"page","link":"https:\/\/lawfactory-frankfurt.de\/de\/zwangsvollstreckung-und-inkasso\/","title":{"rendered":"Zwangsvollstreckung und Inkasso"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13619\" class=\"elementor elementor-13619\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09c8494 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"09c8494\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2db8312\" data-id=\"2db8312\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ace84d fdvfdfgfd elementor-widget elementor-widget-homau-slider-two\" data-id=\"5ace84d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau-slider-two.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<script>\r\n\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\t \"use strict\";\r\n\t\t\t\tfunction mainSlider() {\r\n\t\t\t        var BasicSlider = $('.slider-active');\r\n\t\t\t        BasicSlider.on('init', function (e, slick) {\r\n\t\t\t            var $firstAnimatingElements = $('.single-slider:first-child').find('[data-animation]');\r\n\t\t\t            doAnimations($firstAnimatingElements);\r\n\t\t\t        });\r\n\t\t\t        BasicSlider.on('beforeChange', function (e, slick, currentSlide, nextSlide) {\r\n\t\t\t            var $animatingElements = $('.single-slider[data-slick-index=\"' + nextSlide + '\"]').find('[data-animation]');\r\n\t\t\t            doAnimations($animatingElements);\r\n\t\t\t        });\r\n\t\t\t        BasicSlider.slick({\r\n\t\t\t            autoplay: true,\r\n\t\t\t            autoplaySpeed: 8000,\r\n\t\t\t            dots: false,\r\n\t\t\t            fade: true,\r\n\t\t\t            arrows: true,\r\n\t\t\t            prevArrow: '<span class=\"prev\"><i class=\"fas fa-chevron-left\"><\/i><\/span>',\r\n\t\t\t            nextArrow: '<span class=\"next\"><i class=\"fas fa-chevron-right\"><\/i><\/span>',\r\n\t\t\t            responsive: [\r\n\t\t\t                {\r\n\t\t\t                    breakpoint: 767,\r\n\t\t\t                    settings: {\r\n\t\t\t                        arrows: false\r\n\t\t\t                    }\r\n\t\t\t                }\r\n\t\t\t            ]\r\n\t\t\t        });\r\n\r\n\t\t\t        function doAnimations(elements) {\r\n\t\t\t            var animationEndEvents = 'webkitAnimationEnd mozAnimationEnd MSAnimationEnd oanimationend animationend';\r\n\t\t\t            elements.each(function () {\r\n\t\t\t                var $this = $(this);\r\n\t\t\t                var $animationDelay = $this.data('delay');\r\n\t\t\t                var $animationType = 'animated ' + $this.data('animation');\r\n\t\t\t                $this.css({\r\n\t\t\t                    'animation-delay': $animationDelay,\r\n\t\t\t                    '-webkit-animation-delay': $animationDelay\r\n\t\t\t                });\r\n\t\t\t                $this.addClass($animationType).one(animationEndEvents, function () {\r\n\t\t\t                    $this.removeClass($animationType);\r\n\t\t\t                });\r\n\t\t\t            });\r\n\t\t\t        }\r\n\t\t\t    }\r\n\t\t\t    mainSlider();\r\n\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t<script>\r\n\t\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\t\t \"use strict\";\r\n\t\t\t\t\t$('.slider-video').magnificPopup({\r\n\t\t\t\t\t\tdisableOn: 700,\r\n\t\t\t\t\t\ttype: 'iframe',\r\n\t\t\t\t\t\tmainClass: 'mfp-fade',\r\n\t\t\t\t\t\tremovalDelay: 160,\r\n\t\t\t\t\t\tpreloader: false,\r\n\r\n\t\t\t\t\t\tfixedContentPos: false\r\n\t\t\t\t\t});\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t <div class=\"slider-area slider-active\">\r\n\t\t\t \r\n\r\n\t        <div class=\"single-slider\">\r\n\t\t\t<div class=\"image-layout\" style=\"background-image:url( https:\/\/lawfactory-frankfurt.de\/wp-content\/uploads\/2024\/10\/skyline-3660778_1280.jpg )\"><\/div>\r\n\t            <div class=\"container\">\r\n\t                <div class=\"justify-content-center \">\r\n\t                    <div class=\"col-lg-12\">\r\n\t                        <div class=\"slider-content\">\r\n\t                            <div class=\"sub-title\" data-animation=\"fadeInLeft\" data-delay=\"1s\"><h3><span style=\"text-decoration: underline;color: #fff\">Zwangsvollstreckung  &amp; Inkasso <\/span><\/h3>\nEffiziente L\u00f6sungen f\u00fcr Ihre Forderungen \u2013 wir bringen Ihre Anspr\u00fcche durch\n<div id=\"simple-translate\" class=\"simple-translate-system-theme\">\n<div>\n<div class=\"simple-translate-button isShow\" style=\"height: 22px;width: 22px;top: 97px;left: -9px\"><\/div>\n<div class=\"simple-translate-panel \" style=\"width: 300px;height: 200px;top: 0px;left: 0px;font-size: 13px\">\n<div class=\"simple-translate-result-wrapper\" style=\"overflow: hidden\">\n<div class=\"simple-translate-move\"><\/div>\n<div class=\"simple-translate-result-contents\">\n<p class=\"simple-translate-result\" dir=\"auto\"><\/p>\n<p class=\"simple-translate-candidate\" dir=\"auto\"><\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\r\n\t                            <div class=\"slider-dec\" data-animation=\"fadeInLeft\" data-delay=\"1s\"><p>Wir setzen Ihre Forderungen mit Engagement und Fachkompetenz durch, damit Sie Ihre Anspr\u00fcche schnell und effektiv geltend machen k\u00f6nnen. Unser erfahrenes Team kennt alle rechtlichen M\u00f6glichkeiten und entwickelt ma\u00dfgeschneiderte L\u00f6sungen f\u00fcr Ihre Situation. Vertrauen Sie auf uns, um Ihre finanziellen Interessen zu sch\u00fctzen!<\/p><\/div>\r\n\t                            <div class=\"homau-slider2-btnss\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"blob-btn\" href=\"#\" data-animation=\"fadeInLeft\" data-delay=\"1s\">Zu den Downloads<i class=\"flaticon-right-arrow\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t                            \t \t\t\t\t                    \t<div class=\"slider-video-btn\" data-animation=\"\" data-delay=\"1s\">\r\n\t\t\t\t                        \t<a href=\"\" class=\"slider-video\">\r\n\t\t\t\t                        \t\t<i class=\"flaticon-play-button-1\"><\/i>\r\n\t\t\t\t                        \t<\/a>\r\n\t\t\t\t                        \t\t\t\t\t                        <\/div>\r\n\t\t\t\t\t                \t                            <\/div>\r\n\t                        <\/div>\r\n\t                    <\/div>\r\n\t                    \t                <\/div>\r\n\t            <\/div>\r\n\t        <\/div>\r\n\t\t\t\t    <\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-046c903 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"046c903\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b8349c\" data-id=\"1b8349c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-cce6b5e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"cce6b5e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1979655 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1979655\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61573d6 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"61573d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6a8e17 elementor-widget elementor-widget-heading\" data-id=\"c6a8e17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LAW FACTORY<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb9671 elementor-widget elementor-widget-heading\" data-id=\"2eb9671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ihre Anspr\u00fcche \u2013 unser Auftrag! Effiziente L\u00f6sungen f\u00fcr erfolgreiche Durchsetzung.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4e3e83 elementor-widget elementor-widget-text-editor\" data-id=\"f4e3e83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWir bringen Ihre Forderungen schnell und effizient zu ihrem Ziel \u2013 mit umfassender Expertise in Zwangsvollstreckung und Inkasso. Unser engagiertes Team kennt alle Strategien, um Ihre Anspr\u00fcche durchzusetzen. Vertrauen Sie uns, um Ihre finanziellen Interessen zu sch\u00fctzen!\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ef3236 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6ef3236\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-678a69f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"678a69f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1c27602 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1c27602\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b199a elementor-widget elementor-widget-icon-box\" data-id=\"a8b199a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFachkundige Beratung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUnser Team besteht aus erfahrenen Spezialisten, die sich auf Zwangsvollstreckung und Inkasso spezialisiert haben, um Ihnen fundierte rechtliche Unterst\u00fctzung zu bieten.\n\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4dfe01 elementor-widget elementor-widget-icon-box\" data-id=\"c4dfe01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIndividuelle L\u00f6sungen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tJedes Inkassoverfahren wird individuell auf Ihre Bed\u00fcrfnisse und Anforderungen zugeschnitten, um die besten Ergebnisse zu erzielen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bac5e81 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"bac5e81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d55c87 elementor-widget elementor-widget-icon-box\" data-id=\"2d55c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEffiziente Durchsetzung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir nutzen bew\u00e4hrte Methoden und Strategien, um Ihre Forderungen schnell und erfolgreich einzutreiben, sodass Sie sich auf Ihr Kerngesch\u00e4ft konzentrieren k\u00f6nnen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13f717c elementor-widget elementor-widget-icon-box\" data-id=\"13f717c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTransparente Kommunikation\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir halten Sie jederzeit \u00fcber den Stand der Dinge informiert und stellen sicher, dass Sie \u00fcber alle Entwicklungen im Prozess Bescheid wissen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47b4fe4 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"47b4fe4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8c931bb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8c931bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8dccf0 elementor-widget elementor-widget-heading\" data-id=\"c8dccf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LAW FACTORY<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15a1dfd elementor-widget elementor-widget-heading\" data-id=\"15a1dfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vertrauen Sie auf unsere Kompetenz \u2013 wir holen zur\u00fcck, was Ihnen zusteht!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2600be elementor-widget elementor-widget-text-editor\" data-id=\"d2600be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMit uns an Ihrer Seite profitieren Sie von einer professionellen und pers\u00f6nlichen Betreuung w\u00e4hrend des gesamten Inkassoprozesses. Wir setzen uns f\u00fcr Ihre Rechte ein und sorgen daf\u00fcr, dass Ihnen zusteht, was Ihnen zusteht. Lassen Sie uns gemeinsam Ihre finanziellen Herausforderungen meistern!\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5541555 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"5541555\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-26d9d8c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"26d9d8c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-79fa3a6 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"79fa3a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb511f5 elementor-widget elementor-widget-icon-box\" data-id=\"eb511f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tHohe Erfolgsquote\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDurch unsere gezielte Vorgehensweise erreichen wir eine hohe Erfolgsquote bei der Eintreibung offener Forderungen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-598ce6a elementor-widget elementor-widget-icon-box\" data-id=\"598ce6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFlexibilit\u00e4t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUnser Ansatz ist flexibel, sodass wir uns schnell an Ver\u00e4nderungen in der Situation oder im Markt anpassen k\u00f6nnen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10a20ef e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"10a20ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-448fe6e elementor-widget elementor-widget-icon-box\" data-id=\"448fe6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRechtliche Absicherung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir stellen sicher, dass alle Ma\u00dfnahmen rechtlich einwandfrei sind, um Ihre Anspr\u00fcche wirksam zu sch\u00fctzen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad67b8c elementor-widget elementor-widget-icon-box\" data-id=\"ad67b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNachhaltige Beziehungen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir legen Wert auf eine langfristige Zusammenarbeit und bauen vertrauensvolle Beziehungen zu unseren Mandanten auf, um wiederkehrende Probleme zu vermeiden.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dada915 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"dada915\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-94bb47e\" data-id=\"94bb47e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d66d73 elementor-widget elementor-widget-homau-title\" data-id=\"0d66d73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-boxs\">\r\n\t\t\t<div class=\"title-box\">\r\n\t\t\t\t\t\t\t\t<span class=\"small-title\">LAW FACTORY<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"title-hadding\"><span><p>Ihre Forderungen in guten H\u00e4nden \u2013 wir setzen durch, was Ihnen zusteht!<\/p>\n<\/span><\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-600e3cd elementor-widget elementor-widget-text-editor\" data-id=\"600e3cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir sind Ihr verl\u00e4sslicher Partner in der Zwangsvollstreckung und im Inkasso, weil wir \u00fcber umfassende Fachkenntnisse und Erfahrung verf\u00fcgen. Mit unserem engagierten Team setzen wir Ihre Forderungen schnell und effektiv durch, um Ihre finanziellen Interessen bestm\u00f6glich zu sch\u00fctzen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f23ad2f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"f23ad2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-476fb91 elementor-invisible\" data-id=\"476fb91\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbcf189 elementor-widget elementor-widget-homau_iconbox\" data-id=\"cbcf189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau_iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"iconbox\">\r\n                <div class=\"iconbox-icon\">\r\n                    <i class=\"flaticon flaticon-plane\"><\/i>\r\n                <\/div>\r\n                <div class=\"iconbox-dec\">\r\n                    <h5 class=\"iconbox-title\">\r\n                         <a href=\"\">                        <span>Kundenspezifische Strategien<\/span>\r\n                         <\/a>                    <\/h5>\r\n                    <p>Wir entwickeln individuelle Inkassostrategien, die speziell auf Ihre Branche und die jeweiligen Kunden zugeschnitten sind.<\/p>\r\n                <\/div>\r\n                            <\/div>\r\n                   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5508a7d elementor-widget elementor-widget-homau_iconbox\" data-id=\"5508a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau_iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"iconbox\">\r\n                <div class=\"iconbox-icon\">\r\n                    <i class=\"fas fa-hand-holding-heart\"><\/i>\r\n                <\/div>\r\n                <div class=\"iconbox-dec\">\r\n                    <h5 class=\"iconbox-title\">\r\n                         <a href=\"\">                        <span>Erfolgsgarantie<\/span>\r\n                         <\/a>                    <\/h5>\r\n                    <p>Bei bestimmten Dienstleistungen bieten wir eine erfolgsabh\u00e4ngige Verg\u00fctung an, sodass Sie nur zahlen, wenn wir erfolgreich sind.<\/p>\r\n                <\/div>\r\n                            <\/div>\r\n                   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f48dc4b elementor-invisible\" data-id=\"f48dc4b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff81a90 elementor-widget elementor-widget-homau_iconbox\" data-id=\"ff81a90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau_iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"iconbox\">\r\n                <div class=\"iconbox-icon\">\r\n                    <i class=\"fab fa-autoprefixer\"><\/i>\r\n                <\/div>\r\n                <div class=\"iconbox-dec\">\r\n                    <h5 class=\"iconbox-title\">\r\n                         <a href=\"\">                        <span>Umfassende Marktkenntnis<\/span>\r\n                         <\/a>                    <\/h5>\r\n                    <p>Unser Team verf\u00fcgt \u00fcber umfassende Kenntnisse der verschiedenen Marktbedingungen, was uns erm\u00f6glicht, effektivere Ma\u00dfnahmen zu ergreifen.<\/p>\r\n                <\/div>\r\n                            <\/div>\r\n                   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ada3f34 elementor-widget elementor-widget-homau_iconbox\" data-id=\"ada3f34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau_iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"iconbox\">\r\n                <div class=\"iconbox-icon\">\r\n                    <i class=\"icon icon-agenda\"><\/i>\r\n                <\/div>\r\n                <div class=\"iconbox-dec\">\r\n                    <h5 class=\"iconbox-title\">\r\n                         <a href=\"\">                        <span>Schulung und Weiterbildung<\/span>\r\n                         <\/a>                    <\/h5>\r\n                    <p>Unser Team wird regelm\u00e4\u00dfig geschult, um auf dem neuesten Stand der rechtlichen Entwicklungen und Inkassopraktiken zu bleiben.<\/p>\r\n                <\/div>\r\n                            <\/div>\r\n                   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-af20083 elementor-invisible\" data-id=\"af20083\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ce1d93 elementor-widget elementor-widget-homau_iconbox\" data-id=\"2ce1d93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau_iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"iconbox\">\r\n                <div class=\"iconbox-icon\">\r\n                    <i class=\"icon icon-stats\"><\/i>\r\n                <\/div>\r\n                <div class=\"iconbox-dec\">\r\n                    <h5 class=\"iconbox-title\">\r\n                         <a href=\"\">                        <span>Schnelle Bearbeitungszeiten:<\/span>\r\n                         <\/a>                    <\/h5>\r\n                    <p>Wir garantieren z\u00fcgige Bearbeitungszeiten, sodass Ihre Forderungen schnell eingetrieben werden, ohne unn\u00f6tige Verz\u00f6gerungen.<\/p>\r\n                <\/div>\r\n                            <\/div>\r\n                   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcb5da6 elementor-widget elementor-widget-homau_iconbox\" data-id=\"dcb5da6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau_iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"iconbox\">\r\n                <div class=\"iconbox-icon\">\r\n                    <i class=\"icon icon-swarm\"><\/i>\r\n                <\/div>\r\n                <div class=\"iconbox-dec\">\r\n                    <h5 class=\"iconbox-title\">\r\n                         <a href=\"\">                        <span>Technologische Unterst\u00fctzung<\/span>\r\n                         <\/a>                    <\/h5>\r\n                    <p>Wir nutzen moderne Software und Technologien, um den Inkassoprozess effizienter zu gestalten und die Kommunikation zu optimieren.<\/p>\r\n                <\/div>\r\n                            <\/div>\r\n                   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4bde78a elementor-invisible\" data-id=\"4bde78a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f4155a elementor-widget elementor-widget-homau_iconbox\" data-id=\"9f4155a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau_iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"iconbox\">\r\n                <div class=\"iconbox-icon\">\r\n                    <i class=\"ico ico-coins-1\"><\/i>\r\n                <\/div>\r\n                <div class=\"iconbox-dec\">\r\n                    <h5 class=\"iconbox-title\">\r\n                         <a href=\"\">                        <span>Optimale Dokumentation<\/span>\r\n                         <\/a>                    <\/h5>\r\n                    <p>Wir sorgen daf\u00fcr, dass alle relevanten Dokumente und Nachweise professionell und vollst\u00e4ndig aufbereitet sind, um rechtliche Schritte zu erleichtern.<\/p>\r\n                <\/div>\r\n                            <\/div>\r\n                   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4c5348 elementor-widget elementor-widget-homau_iconbox\" data-id=\"c4c5348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau_iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"iconbox\">\r\n                <div class=\"iconbox-icon\">\r\n                    <i class=\"icon icon-diploma\"><\/i>\r\n                <\/div>\r\n                <div class=\"iconbox-dec\">\r\n                    <h5 class=\"iconbox-title\">\r\n                         <a href=\"\">                        <span>Internationale Expertise<\/span>\r\n                         <\/a>                    <\/h5>\r\n                    <p>Bei Bedarf bieten wir auch Unterst\u00fctzung im internationalen Inkasso und kennen die verschiedenen rechtlichen Rahmenbedingungen in anderen L\u00e4ndern.<\/p>\r\n                <\/div>\r\n                            <\/div>\r\n                   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-88734b4 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"88734b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4150890 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4150890\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-659cfde elementor-widget elementor-widget-homau-title\" data-id=\"659cfde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"homau-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-boxs\">\r\n\t\t\t<div class=\"title-box\">\r\n\t\t\t\t\t\t\t\t<span class=\"small-title\">Bewertungen<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da7f39b elementor-widget elementor-widget-text-editor\" data-id=\"da7f39b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere Bewertungen zeigen durchweg hohe Kundenzufriedenheit. Kunden loben besonders die Qualit\u00e4t, den Service und die Zuverl\u00e4ssigkeit. Insgesamt spiegeln die R\u00fcckmeldungen Vertrauen und eine hohe Empfehlungsbereitschaft wider.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44f376d elementor-widget elementor-widget-elementskit-testimonial\" data-id=\"44f376d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"elementskit-testimonial-slider ekit_testimonial_style_5 arrow_inside \" data-config=\"{&quot;rtl&quot;:false,&quot;arrows&quot;:false,&quot;dots&quot;:false,&quot;pauseOnHover&quot;:true,&quot;autoplay&quot;:true,&quot;speed&quot;:1000,&quot;slidesPerGroup&quot;:1,&quot;slidesPerView&quot;:3,&quot;loop&quot;:false,&quot;spaceBetween&quot;:15,&quot;breakpoints&quot;:{&quot;320&quot;:{&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:10},&quot;768&quot;:{&quot;slidesPerView&quot;:2,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:10},&quot;1024&quot;:{&quot;slidesPerView&quot;:3,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:15}}}\">\n\t<div class=\"ekit-main-swiper swiper\">\n\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider elementskit-testimonial-slider-block-style elementskit-testimonial-slider-block-style-two   elementor-repeater-item-f132993\" >\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-header\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-icon-content elementskit-watermark-icon \">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\"><p>\"Die Beratung war sehr  professionell und verst\u00e4ndlich. Jeder Schritt wurde mir genau erkl\u00e4rt. Ich hatte jederzeit das Gef\u00fchl, in besten H\u00e4nden zu sein.\"<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-bio\">\n\t\t\t\t\t\t\t\t<div class=\"elementkit-commentor-details \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-image ekit-testimonial--avatar\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/lawfactory-frankfurt.de\/wp-content\/uploads\/2024\/09\/cropped-LogoLaw-2.png\" title=\"\" alt=\"\" class=\"\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">Thomas M\u00fcller<\/strong>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider elementskit-testimonial-slider-block-style elementskit-testimonial-slider-block-style-two   elementor-repeater-item-e7a96ee\" >\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-header\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-icon-content elementskit-watermark-icon \">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\"><p>\"Die Kanzlei war stets engagiert und gut erreichbar. Meine Anliegen wurden ernst genommen. Ein verl\u00e4sslicher Partner f\u00fcr alle rechtlichen Fragen.\"<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-bio\">\n\t\t\t\t\t\t\t\t<div class=\"elementkit-commentor-details \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-image ekit-testimonial--avatar\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/lawfactory-frankfurt.de\/wp-content\/uploads\/2024\/09\/cropped-LogoLaw-2.png\" title=\"\" alt=\"\" class=\"\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">Eugen Markus<\/strong>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider elementskit-testimonial-slider-block-style elementskit-testimonial-slider-block-style-two   elementor-repeater-item-dca996b\" >\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-header\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-icon-content elementskit-watermark-icon \">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\"><p>\"Schnelle und pr\u00e4zise Antworten auf all meine Fragen. Die Kommunikation war unkompliziert und klar. Absolut empfehlenswert f\u00fcr eine effiziente Vertretung.\"<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-bio\">\n\t\t\t\t\t\t\t\t<div class=\"elementkit-commentor-details \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-image ekit-testimonial--avatar\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/lawfactory-frankfurt.de\/wp-content\/uploads\/2024\/09\/cropped-LogoLaw-2.png\" title=\"\" alt=\"\" class=\"\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">Lisa F\u00fcller<\/strong>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider elementskit-testimonial-slider-block-style elementskit-testimonial-slider-block-style-two   elementor-repeater-item-c200920\" >\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-header\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-icon-content elementskit-watermark-icon \">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\"><p>\"Sehr empathisch und l\u00f6sungsorientiert in jeder Phase. In einer schwierigen Situation hat die Kanzlei mir wirklich weitergeholfen. Ich f\u00fchlte mich rundum unterst\u00fctzt.\"<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-bio\">\n\t\t\t\t\t\t\t\t<div class=\"elementkit-commentor-details \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-image ekit-testimonial--avatar\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/lawfactory-frankfurt.de\/wp-content\/uploads\/2024\/09\/cropped-LogoLaw-2.png\" title=\"\" alt=\"\" class=\"\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">Tarik Chaikun<\/strong>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider elementskit-testimonial-slider-block-style elementskit-testimonial-slider-block-style-two   elementor-repeater-item-fea3d85\" >\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-header\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-icon-content elementskit-watermark-icon \">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\"><p>\"Exzellente Fachkenntnisse und starke Verhandlungsf\u00fchrung. Meine Interessen wurden bestens vertreten. Diese Kanzlei ist definitiv eine Empfehlung wert.\"<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-bio\">\n\t\t\t\t\t\t\t\t<div class=\"elementkit-commentor-details \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-commentor-image ekit-testimonial--avatar\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/lawfactory-frankfurt.de\/wp-content\/uploads\/2024\/09\/cropped-LogoLaw-2.png\" title=\"\" alt=\"\" class=\"\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">Markus Helmer<\/strong>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89584a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"89584a6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b55170\" data-id=\"5b55170\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-93b3208 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"93b3208\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-19d2bc9\" data-id=\"19d2bc9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1758b07\" data-id=\"1758b07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-817c2e2 elementor-widget elementor-widget-heading\" data-id=\"817c2e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontaktieren Sie uns<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c0c89e elementor-widget elementor-widget-text-editor\" data-id=\"3c0c89e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gerne unterst\u00fctzen wir Sie bei Ihrem Anliegen. Kontaktieren Sie uns unverbindlich mit einer kurzen Beschreibung Ihres Falls \u2013 unser Team setzt sich umgehend mit Ihnen in Verbindung, um die n\u00e4chsten Schritte zu besprechen. Wir freuen uns darauf, Ihnen weiterzuhelfen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f8ee83 elementor-widget elementor-widget-text-editor\" data-id=\"5f8ee83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f11244-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"11244\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/13619#wpcf7-f11244-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"11244\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f11244-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"container contact\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Vor- und Nachname\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ihre E-Mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Telefonnummer\" value=\"\" type=\"text\" name=\"your-number\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Thema\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Nachricht\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Senden\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9e8c91 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d9e8c91\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e79b66\" data-id=\"1e79b66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b6f7478 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b6f7478\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e374f51\" data-id=\"e374f51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f354cd5 elementor-widget elementor-widget-heading\" data-id=\"f354cd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcbersicht<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78f8b56 elementor-widget elementor-widget-wp-widget-nav_menu\" data-id=\"78f8b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-nav_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"menu-quick-links-container\"><ul id=\"menu-quick-links\" class=\"menu\"><li id=\"menu-item-16195\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-16195\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/\">Rechtsanwaltskanzlei<\/a><\/li>\n<li id=\"menu-item-12682\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12682\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/steuerkanzlei\/\">Steuerkanzlei<\/a><\/li>\n<li id=\"menu-item-14494\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14494\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/schwerpunkte_recht\/\">Schwerpunkte (Recht)<\/a><\/li>\n<li id=\"menu-item-14495\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14495\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/schwerpunkte_steuer\/\">Schwerpunkte (Steuer)<\/a><\/li>\n<li id=\"menu-item-12917\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12917\"><a href=\"#\">Law Factory<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-12677\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12677\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/unsere-philosophie\/\">Unsere Philosophie<\/a><\/li>\n\t<li id=\"menu-item-16196\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-16196\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/unser-team-recht-2024\/\">Unser Team<\/a><\/li>\n\t<li id=\"menu-item-17000\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17000\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/galerie-2\/\">Galerie<\/a><\/li>\n\t<li id=\"menu-item-16732\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-16732\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/zertifikate\/\">Zertifikate<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-17416\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17416\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/karriere\/\">Karriere<\/a><\/li>\n<li id=\"menu-item-12681\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12681\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/faqs\/\">FAQs<\/a><\/li>\n<li id=\"menu-item-13085\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13085\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/downloads\/\">Downloads<\/a><\/li>\n<li id=\"menu-item-12675\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12675\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/kontakt\/\">Kontakt<\/a><\/li>\n<li id=\"menu-item-12683\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12683\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/impressum\/\">Impressum<\/a><\/li>\n<li id=\"menu-item-12686\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12686\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/datenschutz\/\">Datenschutz<\/a><\/li>\n<li id=\"menu-item-12680\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12680\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/blog\/\">Blog<\/a><\/li>\n<li id=\"menu-item-12914\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12914\"><a href=\"https:\/\/lawfactory-frankfurt.de\/de\/agbs\/\">AGBs<\/a><\/li>\n<\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d4331cd\" data-id=\"d4331cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d080e8 elementor-widget elementor-widget-heading\" data-id=\"0d080e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontakt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b4ad9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e1b4ad9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-placeholder-1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">LAW Factory<br> Voltastra\u00dfe 31 <br>60486\u00a0Frankfurt<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@lawfactory-frankfurt.de\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope-open\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 464c0 26.51-21.49 48-48 48H48c-26.51 0-48-21.49-48-48V200.724a48 48 0 0 1 18.387-37.776c24.913-19.529 45.501-35.365 164.2-121.511C199.412 29.17 232.797-.347 256 .003c23.198-.354 56.596 29.172 73.413 41.433 118.687 86.137 139.303 101.995 164.2 121.512A48 48 0 0 1 512 200.724V464zm-65.666-196.605c-2.563-3.728-7.7-4.595-11.339-1.907-22.845 16.873-55.462 40.705-105.582 77.079-16.825 12.266-50.21 41.781-73.413 41.43-23.211.344-56.559-29.143-73.413-41.43-50.114-36.37-82.734-60.204-105.582-77.079-3.639-2.688-8.776-1.821-11.339 1.907l-9.072 13.196a7.998 7.998 0 0 0 1.839 10.967c22.887 16.899 55.454 40.69 105.303 76.868 20.274 14.781 56.524 47.813 92.264 47.573 35.724.242 71.961-32.771 92.263-47.573 49.85-36.179 82.418-59.97 105.303-76.868a7.998 7.998 0 0 0 1.839-10.967l-9.071-13.196z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@lawfactory-frankfurt.de<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:004969%20264922420\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">DE: 069 264922420<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:004969%20264922420\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">RU 069 264922422<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a6a203 elementor-widget elementor-widget-heading\" data-id=\"1a6a203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teilen Sie uns<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a293725 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a293725\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:?body=https%3A%2F%2Fwww.lawfactory-frankfurt.de%2Fde%2F\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-mail-7\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mail<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lawfactory-frankfurt.de\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.lawfactory-frankfurt.de%2Fde%2F\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Twitter X<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fwww.lawfactory-frankfurt.de\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">LinkedIn<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fwww.lawfactory-frankfurt.de%2Fde%2F\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-pinterest\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 256c0 137-111 248-248 248-25.6 0-50.2-3.9-73.4-11.1 10.1-16.5 25.2-43.5 30.8-65 3-11.6 15.4-59 15.4-59 8.1 15.4 31.7 28.5 56.8 28.5 74.8 0 128.7-68.8 128.7-154.3 0-81.9-66.9-143.2-152.9-143.2-107 0-163.9 71.8-163.9 150.1 0 36.4 19.4 81.7 50.3 96.1 4.7 2.2 7.2 1.2 8.3-3.3.8-3.4 5-20.3 6.9-28.1.6-2.5.3-4.7-1.7-7.1-10.1-12.5-18.3-35.3-18.3-56.6 0-54.7 41.4-107.6 112-107.6 60.9 0 103.6 41.5 103.6 100.9 0 67.1-33.9 113.6-78 113.6-24.3 0-42.6-20.1-36.7-44.8 7-29.5 20.5-61.3 20.5-82.6 0-19-10.2-34.9-31.4-34.9-24.9 0-44.9 25.7-44.9 60.2 0 22 7.4 36.8 7.4 36.8s-24.5 103.8-29 123.2c-5 21.4-3 51.6-.9 71.2C65.4 450.9 0 361.1 0 256 0 119 111 8 248 8s248 111 248 248z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pinterest<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lawfactory-frankfurt.de%2Fde%2F\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-reddit-alien\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M440.3 203.5c-15 0-28.2 6.2-37.9 15.9-35.7-24.7-83.8-40.6-137.1-42.3L293 52.3l88.2 19.8c0 21.6 17.6 39.2 39.2 39.2 22 0 39.7-18.1 39.7-39.7s-17.6-39.7-39.7-39.7c-15.4 0-28.7 9.3-35.3 22l-97.4-21.6c-4.9-1.3-9.7 2.2-11 7.1L246.3 177c-52.9 2.2-100.5 18.1-136.3 42.8-9.7-10.1-23.4-16.3-38.4-16.3-55.6 0-73.8 74.6-22.9 100.1-1.8 7.9-2.6 16.3-2.6 24.7 0 83.8 94.4 151.7 210.3 151.7 116.4 0 210.8-67.9 210.8-151.7 0-8.4-.9-17.2-3.1-25.1 49.9-25.6 31.5-99.7-23.8-99.7zM129.4 308.9c0-22 17.6-39.7 39.7-39.7 21.6 0 39.2 17.6 39.2 39.7 0 21.6-17.6 39.2-39.2 39.2-22 .1-39.7-17.6-39.7-39.2zm214.3 93.5c-36.4 36.4-139.1 36.4-175.5 0-4-3.5-4-9.7 0-13.7 3.5-3.5 9.7-3.5 13.2 0 27.8 28.5 120 29 149 0 3.5-3.5 9.7-3.5 13.2 0 4.1 4 4.1 10.2.1 13.7zm-.8-54.2c-21.6 0-39.2-17.6-39.2-39.2 0-22 17.6-39.7 39.2-39.7 22 0 39.7 17.6 39.7 39.7-.1 21.5-17.7 39.2-39.7 39.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reddit<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.lawfactory-frankfurt.de%2Fde%2F\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Whatsapp<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a326c5c\" data-id=\"a326c5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28597e2 elementor-widget elementor-widget-heading\" data-id=\"28597e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wo Sie uns finden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0fb5ec elementor-widget elementor-widget-html\" data-id=\"e0fb5ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe style=\"height:275px\" src=\"https:\/\/snazzymaps.com\/embed\/660837\" width=\"40%\" height=\"600px\" style=\"border:none;\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a369d03 elementor-widget elementor-widget-heading\" data-id=\"a369d03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parkm\u00f6glichkeiten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67e961a elementor-widget elementor-widget-html\" data-id=\"67e961a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe style=\"height:275px\" src=\"https:\/\/snazzymaps.com\/embed\/660838\" width=\"100%\" height=\"400px\" style=\"border:none;\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Zwangsvollstreckung &amp; Inkasso Effiziente L\u00f6sungen f\u00fcr Ihre Forderungen \u2013 wir bringen Ihre Anspr\u00fcche durch Wir setzen Ihre Forderungen mit Engagement und Fachkompetenz durch, damit Sie Ihre Anspr\u00fcche schnell und effektiv geltend machen k\u00f6nnen. Unser erfahrenes Team kennt alle rechtlichen M\u00f6glichkeiten und entwickelt ma\u00dfgeschneiderte L\u00f6sungen f\u00fcr Ihre Situation. Vertrauen Sie auf uns, um Ihre finanziellen Interessen zu sch\u00fctzen! Zu den Downloads LAW FACTORY Ihre Anspr\u00fcche \u2013 unser Auftrag! Effiziente L\u00f6sungen f\u00fcr erfolgreiche Durchsetzung. Wir bringen Ihre Forderungen schnell und effizient zu ihrem Ziel \u2013 mit umfassender Expertise in Zwangsvollstreckung und Inkasso. Unser engagiertes Team kennt alle Strategien, um Ihre Anspr\u00fcche durchzusetzen. Vertrauen Sie uns, um Ihre finanziellen Interessen zu sch\u00fctzen! Fachkundige Beratung Unser Team besteht aus erfahrenen Spezialisten, die sich auf Zwangsvollstreckung und Inkasso spezialisiert haben, um Ihnen fundierte rechtliche Unterst\u00fctzung zu bieten. Individuelle L\u00f6sungen Jedes Inkassoverfahren wird individuell auf Ihre Bed\u00fcrfnisse und Anforderungen zugeschnitten, um die besten Ergebnisse zu erzielen. Effiziente Durchsetzung Wir nutzen bew\u00e4hrte Methoden und Strategien, um Ihre Forderungen schnell und erfolgreich einzutreiben, sodass Sie sich auf Ihr Kerngesch\u00e4ft konzentrieren k\u00f6nnen. Transparente Kommunikation Wir halten Sie jederzeit \u00fcber den Stand der Dinge informiert und stellen sicher, dass Sie \u00fcber alle Entwicklungen im Prozess Bescheid wissen. LAW FACTORY Vertrauen Sie auf unsere Kompetenz \u2013 wir holen zur\u00fcck, was Ihnen zusteht! Mit uns an Ihrer Seite profitieren Sie von einer professionellen und pers\u00f6nlichen Betreuung w\u00e4hrend des gesamten Inkassoprozesses. Wir setzen uns f\u00fcr Ihre Rechte ein und sorgen daf\u00fcr, dass Ihnen zusteht, was Ihnen zusteht. Lassen Sie uns gemeinsam Ihre finanziellen Herausforderungen meistern! Hohe Erfolgsquote Durch unsere gezielte Vorgehensweise erreichen wir eine hohe Erfolgsquote bei der Eintreibung offener Forderungen. Flexibilit\u00e4t Unser Ansatz ist flexibel, sodass wir uns schnell an Ver\u00e4nderungen in der Situation oder im Markt anpassen k\u00f6nnen. Rechtliche Absicherung Wir stellen sicher, dass alle Ma\u00dfnahmen rechtlich einwandfrei sind, um Ihre Anspr\u00fcche wirksam zu sch\u00fctzen. Nachhaltige Beziehungen Wir legen Wert auf eine langfristige Zusammenarbeit und bauen vertrauensvolle Beziehungen zu unseren Mandanten auf, um wiederkehrende Probleme zu vermeiden. LAW FACTORY Ihre Forderungen in guten H\u00e4nden \u2013 wir setzen durch, was Ihnen zusteht! Wir sind Ihr verl\u00e4sslicher Partner in der Zwangsvollstreckung und im Inkasso, weil wir \u00fcber umfassende Fachkenntnisse und Erfahrung verf\u00fcgen. Mit unserem engagierten Team setzen wir Ihre Forderungen schnell und effektiv durch, um Ihre finanziellen Interessen bestm\u00f6glich zu sch\u00fctzen Kundenspezifische Strategien Wir entwickeln individuelle Inkassostrategien, die speziell auf Ihre Branche und die jeweiligen Kunden zugeschnitten sind. Erfolgsgarantie Bei bestimmten Dienstleistungen bieten wir eine erfolgsabh\u00e4ngige Verg\u00fctung an, sodass Sie nur zahlen, wenn wir erfolgreich sind. Umfassende Marktkenntnis Unser Team verf\u00fcgt \u00fcber umfassende Kenntnisse der verschiedenen Marktbedingungen, was uns erm\u00f6glicht, effektivere Ma\u00dfnahmen zu ergreifen. Schulung und Weiterbildung Unser Team wird regelm\u00e4\u00dfig geschult, um auf dem neuesten Stand der rechtlichen Entwicklungen und Inkassopraktiken zu bleiben. Schnelle Bearbeitungszeiten: Wir garantieren z\u00fcgige Bearbeitungszeiten, sodass Ihre Forderungen schnell eingetrieben werden, ohne unn\u00f6tige Verz\u00f6gerungen. Technologische Unterst\u00fctzung Wir nutzen moderne Software und Technologien, um den Inkassoprozess effizienter zu gestalten und die Kommunikation zu optimieren. Optimale Dokumentation Wir sorgen daf\u00fcr, dass alle relevanten Dokumente und Nachweise professionell und vollst\u00e4ndig aufbereitet sind, um rechtliche Schritte zu erleichtern. Internationale Expertise Bei Bedarf bieten wir auch Unterst\u00fctzung im internationalen Inkasso und kennen die verschiedenen rechtlichen Rahmenbedingungen in anderen L\u00e4ndern. Bewertungen Unsere Bewertungen zeigen durchweg hohe Kundenzufriedenheit. Kunden loben besonders die Qualit\u00e4t, den Service und die Zuverl\u00e4ssigkeit. Insgesamt spiegeln die R\u00fcckmeldungen Vertrauen und eine hohe Empfehlungsbereitschaft wider. &#8220;Die Beratung war sehr professionell und verst\u00e4ndlich. Jeder Schritt wurde mir genau erkl\u00e4rt. Ich hatte jederzeit das Gef\u00fchl, in besten H\u00e4nden zu sein.&#8221; Thomas M\u00fcller &#8220;Die Kanzlei war stets engagiert und gut erreichbar. Meine Anliegen wurden ernst genommen. Ein verl\u00e4sslicher Partner f\u00fcr alle rechtlichen Fragen.&#8221; Eugen Markus &#8220;Schnelle und pr\u00e4zise Antworten auf all meine Fragen. Die Kommunikation war unkompliziert und klar. Absolut empfehlenswert f\u00fcr eine effiziente Vertretung.&#8221; Lisa F\u00fcller &#8220;Sehr empathisch und l\u00f6sungsorientiert in jeder Phase. In einer schwierigen Situation hat die Kanzlei mir wirklich weitergeholfen. Ich f\u00fchlte mich rundum unterst\u00fctzt.&#8221; Tarik Chaikun &#8220;Exzellente Fachkenntnisse und starke Verhandlungsf\u00fchrung. Meine Interessen wurden bestens vertreten. Diese Kanzlei ist definitiv eine Empfehlung wert.&#8221; Markus Helmer Kontaktieren Sie uns Gerne unterst\u00fctzen wir Sie bei Ihrem Anliegen. Kontaktieren Sie uns unverbindlich mit einer kurzen Beschreibung Ihres Falls \u2013 unser Team setzt sich umgehend mit Ihnen in Verbindung, um die n\u00e4chsten Schritte zu besprechen. Wir freuen uns darauf, Ihnen weiterzuhelfen. \u00dcbersicht Kontakt LAW Factory Voltastra\u00dfe 31 60486\u00a0Frankfurt info@lawfactory-frankfurt.de DE: 069 264922420 RU 069 264922422 Teilen Sie uns Mail Facebook Twitter X LinkedIn Pinterest Reddit Whatsapp Wo Sie uns finden Parkm\u00f6glichkeiten<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"home-template.php","meta":{"footnotes":""},"class_list":["post-13619","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lawfactory-frankfurt.de\/de\/wp-json\/wp\/v2\/pages\/13619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lawfactory-frankfurt.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lawfactory-frankfurt.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lawfactory-frankfurt.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lawfactory-frankfurt.de\/de\/wp-json\/wp\/v2\/comments?post=13619"}],"version-history":[{"count":47,"href":"https:\/\/lawfactory-frankfurt.de\/de\/wp-json\/wp\/v2\/pages\/13619\/revisions"}],"predecessor-version":[{"id":16401,"href":"https:\/\/lawfactory-frankfurt.de\/de\/wp-json\/wp\/v2\/pages\/13619\/revisions\/16401"}],"wp:attachment":[{"href":"https:\/\/lawfactory-frankfurt.de\/de\/wp-json\/wp\/v2\/media?parent=13619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}